{"id":11,"date":"2019-10-09T09:53:23","date_gmt":"2019-10-09T00:53:23","guid":{"rendered":"https:\/\/solaniwa.com\/zh-tw\/?page_id=11"},"modified":"2020-01-24T17:51:37","modified_gmt":"2020-01-24T08:51:37","slug":"rooftop_garden","status":"publish","type":"page","link":"https:\/\/solaniwa.com\/zh-tw\/explore\/rooftop_garden\/","title":{"rendered":"\u5ead\u5712\u8207\u8db3\u6e6f"},"content":{"rendered":"<p><!-- \u691c\u7d22\u7528 --><\/p>\n<div class=\"cnt_area\" id=\"cnt_area01\">\n<div class=\"cnt_block\">\n<div class=\"h3_g\">\n<h3>\u5929\u7a7a\u5ead\u5712<\/h3>\n<div class=\"deco_img deco01\"><img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon01_teien.png\" alt=\"\"\/><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon01_teien_sp.png\" alt=\"\"\/><\/div>\n<\/div>\n<div class=\"cnt_g contents_in\" id=\"teien\">\n<div class=\"cnt_img\">\n<div class=\"img_box\"><img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic01_teien.png\" alt=\"\u5ead\u571201\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic01_teien_sp.png\" alt=\"\u5ead\u571201\"><\/div>\n<div class=\"img_box\"><img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic02_teien.png\" alt=\"\u5ead\u571202\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic02_teien_sp.png\" alt=\"\u5ead\u571202\"><\/div>\n<div class=\"img_box\"><img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic03_teien.png\" alt=\"\u5ead\u571203\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic03_teien_sp.png\" alt=\"\u5ead\u571203\">\n<\/div>\n<\/div>\n<div class=\"cnt_box\">\n<div class=\"cnt_title\">\u5728\u7d041,000\u576a\u7684\u8d85\u5927\u578b\u65e5\u672c\u5ead\u5712\u4e2d\uff0c\u7a7f\u8457\u83ef\u9e97\u7684\u6d74\u8863\u60a0\u9592\u4eab\u53d7\u8db3\u6e6f\uff0c\u540c\u6642\u6b23\u8cde\u56db\u5b63\u8b8a\u63db\u7684\u82b1\u8349\u6a39\u6728\uff01<\/div>\n<div class=\"more_box\">\n<input id=\"trigger01\" class=\"grad-trigger\" type=\"checkbox\"><br \/>\n<label class=\"btn_more\" for=\"trigger01\"><\/label><\/p>\n<p class=\"contents_desc\">\u8acb\u8cd3\u5ba2\u5728\u7a7a\u5ead\u6eab\u6cc9\u7684\u5c4b\u9802\u5ee3\u9054\u7d041,000\u576a\u7684\u8d85\u5927\u578b\u65e5\u672c\u5ead\u5712\u4e2d\uff0c\u7a7f\u8457\u83ef\u9e97\u7684\u9928\u5167\u6d74\u8863\u76e1\u60c5\u4eab\u53d7\u8db3\u6e6f\uff0c\u5728\u53ef\u773a\u671b\u5ead\u9662\u7684\u5496\u5561\u5ef3\u54c1\u5690\u751c\u9ede\uff0c\u540c\u6642\u6b23\u8cde\u56db\u5b63\u8b8a\u63db\u7684\u82b1\u8349\u6a39\u6728\u3002\u5929\u7a7a\u5ead\u5712\u56e0\u61c9\u4e0d\u540c\u5b63\u7bc0\u8209\u8fa6\u5404\u7a2e\u6d3b\u52d5\uff0c\u8cd3\u5ba2\u4e5f\u53ef\u4ee5\u5728\u62cd\u7167\u6253\u5361\u666f\u9ede\u7684\u5343\u672c\u9ce5\u5c45\u3001\u6c34\u6d17\u5f01\u5929\u50cf\u7b49\u5730\u9ede\uff0c\u8207\u91cd\u8981\u7684\u53e6\u4e00\u534a\u8a31\u4e0b\u9858\u671b\u7b49\uff0c\u662f\u53ef\u8b93\u8cd3\u5ba2\u4ee5\u81ea\u5df1\u7684\u65b9\u5f0f\u76e1\u60c5\u8cde\u904a\u7684\u65e5\u672c\u5ead\u5712\u3002<\/p>\n<\/div>\n<p><!-- END  .more_box -->\n<\/div>\n<p><!-- END  .cnt_box -->\n<\/div>\n<p><!-- END  .cnt_g -->\n<\/div>\n<p><!-- END .cnt_block -->\n<\/div>\n<p><!-- END  #cnt_area01 --><\/p>\n<div class=\"cnt_area area02\" id=\"cnt_area02\">\n<div class=\"cnt_block\">\n<div class=\"h3_g\">\n<h3><span>\u9b5a\u7642<\/span>\u9b5a\u96c6\u5bb6<\/h3>\n<div class=\"deco_img deco02\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon02_teien.png\" alt=\"\"\/><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon02_teien_sp.png\" alt=\"\"\/><\/div>\n<\/div>\n<div class=\"cnt_g contents_in\" id=\"therapy\">\n<div class=\"cnt_img\">\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic04_teien.png\" alt=\"\u5ead\u571204\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic04_teien_sp.png\" alt=\"\u5ead\u571204\">\n<\/div>\n<\/div>\n<div class=\"cnt_box\">\n<div class=\"cnt_title\">\u7a31\u70ba\u91ab\u751f\u9b5a\u7684\u9b5a\u5152\u5011\u53ef\u63d0\u4f9b\u9b5a\u7642\u670d\u52d9\uff0c\u5354\u52a9\u60a8\u8001\u820a\u7684\u76ae\u819a\u89d2\u8cea\u5c64\u518d\u751f\uff01<\/div>\n<div class=\"more_box\">\n<input id=\"trigger02\" class=\"grad-trigger\" type=\"checkbox\"><br \/>\n<label class=\"btn_more\" for=\"trigger02\"><\/label><\/p>\n<p class=\"contents_desc\">\u5929\u7a7a\u5ead\u5712\u7684\u8db3\u6e6f\u65c1\u7684\u5c0f\u5c4b\u6709\u63d0\u4f9b\u9b5a\u7642\u670d\u52d9\uff0c\u7a31\u70ba\u91ab\u751f\u9b5a\u7684\u9b5a\u5152\u5011\u6703\u5403\u6389\u60a8\u8001\u820a\u7684\u76ae\u819a\u89d2\u8cea\u5c64\uff0c\u9810\u671f\u53ef\u5e36\u4f86\u8b77\u819a\u7684\u6548\u679c\u53ca\u7642\u7652\u6548\u679c\u3002<\/p>\n<\/div>\n<p><!-- END  .more_box -->\n<\/div>\n<p><!-- END  .cnt_box -->\n<\/div>\n<p><!-- END  .cnt_g -->\n<\/div>\n<p><!-- END .cnt_block -->\n<\/div>\n<p><!-- END  #cnt_area01 --><\/p>\n<div class=\"cnt_area\" id=\"cnt_area03\">\n<div class=\"cnt_block\">\n<div class=\"h3_g\">\n<h3>\u7a7a\u5ead\u5ee3\u5834<\/h3>\n<div class=\"deco_img deco03\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon03_teien.png\" alt=\"\"\/><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon03_teien_sp.png\" alt=\"\"\/>\n<\/div>\n<\/div>\n<div class=\"cnt_g contents_in\" id=\"hiroba\">\n<div class=\"cnt_img\">\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic05_teien.png\" alt=\"\u5ead\u571205\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic05_teien_sp.png\" alt=\"\u5ead\u571205\">\n<\/div>\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic06_teien.png\" alt=\"\u5ead\u571206\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic06_teien_sp.png\" alt=\"\u5ead\u571206\">\n<\/div>\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic07_teien.png\" alt=\"\u5ead\u571207\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic07_teien_sp.png\" alt=\"\u5ead\u571207\">\n<\/div>\n<\/div>\n<div class=\"cnt_box\">\n<div class=\"cnt_title\">\u4f9d\u64da\u4e0d\u540c\u5b63\u7bc0\u8209\u8fa6\u5404\u7a2e\u6d3b\u52d5\u7684\u5ead\u5712\u4e2d\u592e\u5ee3\u5834\u3002\u5927\u7011\u5e03\u98db\u6563\u7684\u6c34\u82b1\u6975\u5177\u6c23\u52e2\uff01<\/div>\n<div class=\"more_box\">\n<input id=\"trigger03\" class=\"grad-trigger\" type=\"checkbox\"><br \/>\n<label class=\"btn_more\" for=\"trigger03\"><\/label><\/p>\n<p class=\"contents_desc\">\u7a7a\u5ead\u5ee3\u5834\u4f4d\u65bc\u5929\u7a7a\u5ead\u5712\u4e2d\u592e\u7684\u5927\u7011\u5e03\u524d\u65b9\u3002\u7a7a\u5ead\u5ee3\u5834\u6703\u4f9d\u64da\u4e0d\u540c\u5b63\u7bc0\u8209\u8fa6\u5404\u7a2e\u8868\u6f14\u8207\u6d3b\u52d5\u3002\u8a73\u7d30\u8cc7\u8a0a\u8acb\u53c3\u95b1\u7db2\u7ad9\u4e2d\u7684\u300c\u8868\u6f14\u884c\u7a0b\u8868\u300d\u3002<\/p>\n<\/div>\n<p><!-- END  .more_box -->\n<\/div>\n<p><!-- END  .cnt_box -->\n<\/div>\n<p><!-- END  .cnt_g -->\n<\/div>\n<p><!-- END .cnt_block -->\n<\/div>\n<p><!-- END  #cnt_area01 --><\/p>\n<div class=\"cnt_area area02\" id=\"cnt_area04\">\n<div class=\"cnt_block\">\n<div class=\"h3_g\">\n<h3>\u5929\u7a7a\u8db3\u6e6f<\/h3>\n<div class=\"deco_img deco04\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon04_teien.png\" alt=\"\"\/><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon04_teien_sp.png\" alt=\"\"\/>\n<\/div>\n<\/div>\n<div class=\"cnt_g contents_in\" id=\"ashiyu\">\n<div class=\"cnt_img\">\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic08_teien.png\" alt=\"\u5ead\u571208\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic08_teien_sp.png\" alt=\"\u5ead\u571208\">\n<\/div>\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic09_teien.png\" alt=\"\u5ead\u571209\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic09_teien_sp.png\" alt=\"\u5ead\u571209\">\n<\/div>\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic10_teien.png\" alt=\"\u5ead\u571210\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic10_teien_sp.png\" alt=\"\u5ead\u571210\">\n<\/div>\n<\/div>\n<div class=\"cnt_box\">\n<div class=\"cnt_title\">\u6cbf\u8457\u5ead\u5712\u7684\u77ed\u908a\u8a2d\u6709\u4e00\u6574\u6392\u6975\u70ba\u5bec\u655e\u4e14\u5b8c\u5584\u7684\u8db3\u6e6f\uff01<\/div>\n<div class=\"more_box\">\n<input id=\"trigger04\" class=\"grad-trigger\" type=\"checkbox\"><br \/>\n<label class=\"btn_more\" for=\"trigger04\"><\/label><\/p>\n<p class=\"contents_desc\">\u5929\u7a7a\u5ead\u5712\u7684\u8db3\u6e6f\u662f\u7a7a\u5ead\u6eab\u6cc9\u4e2d\u6700\u70ba\u63a8\u85a6\u7684\u77e5\u540d\u5730\u9ede\u3002\u6cbf\u8457\u5ead\u5712\u7684\u77ed\u908a\u8a2d\u6709\u4e00\u6574\u6392\u6975\u70ba\u5bec\u655e\u4e14\u5b8c\u5584\u7684\u8db3\u6e6f\u3002\u4e00\u908a\u6d78\u6ce1\u8db3\u6e6f\uff0c\u540c\u6642\u6b23\u8cde\u5ee3\u5927\u7684\u65e5\u672c\u5ead\u5712\uff0c\u8b93\u8cd3\u5ba2\u8eab\u5fc3\u7686\u7372\u5f97\u6d17\u6ecc\u3002<\/p>\n<\/div>\n<p><!-- END  .more_box -->\n<\/div>\n<p><!-- END  .cnt_box -->\n<\/div>\n<p><!-- END  .cnt_g -->\n<\/div>\n<p><!-- END .cnt_block -->\n<\/div>\n<p><!-- END  #cnt_area01 --><\/p>\n<div class=\"cnt_area\" id=\"cnt_area05\">\n<div class=\"cnt_block\">\n<div class=\"h3_g\">\n<h3>\u6c34\u6d17\u5f01\u5929\u5bae<\/h3>\n<\/div>\n<div class=\"cnt_g contents_in\" id=\"benten\">\n<div class=\"cnt_img\">\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic11_teien.png\" alt=\"\u5ead\u571211\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic11_teien_sp.png\" alt=\"\u5ead\u571211\">\n<\/div>\n<\/div>\n<div class=\"cnt_box\">\n<div class=\"cnt_title\">\u6c34\u6d17\u5f01\u5929\u795e\u50cf\u7531\u4f5b\u50cf\u5de5\u5320\u7cbe\u5fc3\u96d5\u523b\uff0c\u8acb\u60a8\u8207\u91cd\u8981\u7684\u4eba\u4e00\u8d77\u5728\u6b64\u7948\u798f\uff01<\/div>\n<div class=\"more_box\">\n<input id=\"trigger05\" class=\"grad-trigger\" type=\"checkbox\"><br \/>\n<label class=\"btn_more\" for=\"trigger05\"><\/label><\/p>\n<p class=\"contents_desc\">\u5750\u93ae\u65bc\u5929\u7a7a\u5ead\u5712\u4e2d\u6700\u9ad8\u4f4d\u7f6e\u7684\u662f\u7531\u4f5b\u50cf\u5de5\u5320\u7cbe\u5fc3\u96d5\u523b\u7684\u6c34\u6d17\u5f01\u5929\u795e\u50cf\u3002\u5f9e\u6c34\u6d17\u5f01\u5929\u53ef\u4ee5\u4e00\u89bd\u5ead\u5712\u7684\u7f8e\u9e97\u666f\u8272\uff0c\u56e0\u6b64\u662f\u975e\u5e38\u53d7\u6b61\u8fce\u7684\u300c\u62cd\u7167\u6253\u5361\u666f\u9ede\u300d\u3002<\/p>\n<\/div>\n<p><!-- END  .more_box -->\n<\/div>\n<p><!-- END  .cnt_box -->\n<\/div>\n<p><!-- END  .cnt_g -->\n<\/div>\n<p><!-- END .cnt_block -->\n<\/div>\n<p><!-- END  #cnt_area01 --><\/p>\n<div class=\"cnt_area area02\" id=\"cnt_area06\">\n<div class=\"cnt_block\">\n<div class=\"h3_g\">\n<h3>\u7a7a\u5ead\u5e9a\u7533\u5802<\/h3>\n<div class=\"deco_img deco05\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon05_teien.png\" alt=\"\"\/><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon05_teien_sp.png\" alt=\"\"\/>\n<\/div>\n<\/div>\n<div class=\"cnt_g contents_in\" id=\"koshindo\">\n<div class=\"cnt_img\">\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic12_teien.png\" alt=\"\u5ead\u571212\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic12_teien_sp.png\" alt=\"\u5ead\u571212\">\n<\/div>\n<\/div>\n<div class=\"cnt_box\">\n<div class=\"cnt_title\">\u5c07\u300cMusubi Chan\u300d\u540a\u639b\u5728\u7a7a\u5ead\u5e9a\u7533\u5802\uff08Soraniwa Koshindou\uff09\uff0c\u7948\u6c42\u5be6\u73fe\u9858\u671b\u5427\uff01<\/div>\n<div class=\"more_box\">\n<input id=\"trigger06\" class=\"grad-trigger\" type=\"checkbox\"><br \/>\n<label class=\"btn_more\" for=\"trigger06\"><\/label><\/p>\n<p class=\"contents_desc\">\u7a7a\u5ead\u5e9a\u7533\u5802\u4ee5\u53e4\u4ee3\u7684\u9053\u6559\u7fd2\u4fd7\u70ba\u539f\u578b\uff0c\u8b93\u8cd3\u5ba2\u53ef\u5728\u300cMusubi Chan\u300d\u4e0a\u5beb\u4e0b\u7948\u6c42\u7684\u9858\u671b\u4e26\u540a\u639b\u5728\u5e9a\u7533\u5802\u3002\u5c0f\u9593\u7269\u5f01\u5929\u5802\uff082F\u8cfc\u7269\u6a6b\u753a\uff09\u6709\u92b7\u552e\u300cMusubi Chan\u300d\u3002<\/p>\n<\/div>\n<p><!-- END  .more_box -->\n<\/div>\n<p><!-- END  .cnt_box -->\n<\/div>\n<p><!-- END  .cnt_g -->\n<\/div>\n<p><!-- END .cnt_block -->\n<\/div>\n<p><!-- END  #cnt_area01 --><\/p>\n<div class=\"cnt_area\" id=\"cnt_area07\">\n<div class=\"cnt_block\">\n<div class=\"h3_g\">\n<h3>\u5343\u672c\u9ce5\u5c45<\/h3>\n<div class=\"deco_img deco06\">\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/icon06_teien_sp.png\" alt=\"\"\/>\n<\/div>\n<\/div>\n<div class=\"cnt_g contents_in\" id=\"tori\">\n<div class=\"cnt_img\">\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic13_teien.png\" alt=\"\u5ead\u571213\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic13_teien_sp.png\" alt=\"\u5ead\u571213\">\n<\/div>\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic14_teien.png\" alt=\"\u5ead\u571214\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic14_teien_sp.png\" alt=\"\u5ead\u571214\">\n<\/div>\n<div class=\"img_box\">\n<img decoding=\"async\" class=\"pc\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic15_teien.png\" alt=\"\u5ead\u571215\"><br \/>\n<img decoding=\"async\" class=\"sp\" src=\"\/zh-tw\/wp-content\/themes\/sora02\/img\/explore\/rooftop_garden\/pic15_teien_sp.png\" alt=\"\u5ead\u571215\">\n<\/div>\n<\/div>\n<div class=\"cnt_box\">\n<div class=\"cnt_title\">\u6b61\u8fce\u5728\u5ead\u5712\u7684\u71b1\u9580\u62cd\u7167\u6253\u5361\u666f\u9ede\u5343\u672c\u9ce5\u5c45\u62cd\u4e0b\u559c\u611b\u7684\u7f8e\u7167\uff01<\/div>\n<div class=\"more_box\">\n<input id=\"trigger07\" class=\"grad-trigger\" type=\"checkbox\"><br \/>\n<label class=\"btn_more\" for=\"trigger07\"><\/label><\/p>\n<p class=\"contents_desc\">\u5343\u672c\u9ce5\u5c45\u70ba\u6c34\u6d17\u5f01\u5929\u5bae\u7684\u53c3\u9053\u9ce5\u5c45\uff0c\u662f\u5e7b\u60f3\u5f9e\u73fe\u4e16\u7a7f\u8d8a\u81f3\u9748\u754c\u7684\u96a7\u9053\u800c\u5927\u53d7\u6b61\u8fce\u7684\u300c\u62cd\u7167\u6253\u5361\u666f\u9ede\u300d\u3002\u8cd3\u5ba2\u53ef\u81ea\u7531\u514d\u8cbb\u4f7f\u7528\u81ea\u52d5\u651d\u5f71\u6a5f\uff0c\u4ee5\u5343\u672c\u9ce5\u5c45\u70ba\u80cc\u666f\u62cd\u51fa\u975e\u5e38\u7cbe\u5f69\u7684\u7167\u7247\uff01\u62cd\u597d\u7684\u7167\u7247\u53ef\u7acb\u5373\u4e0b\u8f09\u3002<\/p>\n<\/div>\n<p><!-- END  .more_box -->\n<\/div>\n<p><!-- END  .cnt_box -->\n<\/div>\n<p><!-- END  .cnt_g -->\n<\/div>\n<p><!-- END .cnt_block -->\n<\/div>\n<p><!-- END  #cnt_area01 --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u5929\u7a7a\u5ead\u5712 \u5728\u7d041,000\u576a\u7684\u8d85\u5927\u578b\u65e5\u672c\u5ead\u5712\u4e2d\uff0c\u7a7f\u8457\u83ef\u9e97\u7684\u6d74\u8863\u60a0\u9592\u4eab\u53d7\u8db3\u6e6f\uff0c\u540c\u6642\u6b23\u8cde\u56db\u5b63\u8b8a\u63db\u7684\u82b1\u8349\u6a39\u6728\uff01 \u8acb\u8cd3\u5ba2 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"explore\/page-rooftop_garden.php","meta":{"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"aioseo_notices":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 07:12:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":""},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/solaniwa.com\/zh-tw\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solaniwa.com\/zh-tw\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solaniwa.com\/zh-tw\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solaniwa.com\/zh-tw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solaniwa.com\/zh-tw\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":6,"href":"https:\/\/solaniwa.com\/zh-tw\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":522,"href":"https:\/\/solaniwa.com\/zh-tw\/wp-json\/wp\/v2\/pages\/11\/revisions\/522"}],"up":[{"embeddable":true,"href":"https:\/\/solaniwa.com\/zh-tw\/wp-json\/wp\/v2\/pages\/7"}],"wp:attachment":[{"href":"https:\/\/solaniwa.com\/zh-tw\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}